{"id":94217,"date":"2026-06-24T08:17:37","date_gmt":"2026-06-24T06:17:37","guid":{"rendered":"https:\/\/lesangles.com\/service\/surf-burger\/"},"modified":"2026-06-29T15:46:00","modified_gmt":"2026-06-29T13:46:00","slug":"surf-burger","status":"publish","type":"tsc_service","link":"https:\/\/lesangles.com\/es\/service\/surf-burger\/","title":{"rendered":"SURF BURGER"},"content":{"rendered":"<p>Dans une ambiance tr\u00e8s seventies, hamburgers, paninis, am\u00e9ricains et croques vous attendent. En terrasse ou en salle, \u00e0 proximit\u00e9 des pistes et du centre du village.<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false},"tsc_cat_service":[1328],"class_list":["post-94217","tsc_service","type-tsc_service","status-publish","hentry","tsc_cat_service-restauration-rapide"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SURF BURGER - Les Angles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lesangles.com\/es\/service\/surf-burger\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SURF BURGER - Les Angles\" \/>\n<meta property=\"og:description\" content=\"Dans une ambiance tr\u00e8s seventies, hamburgers, paninis, am\u00e9ricains et croques vous attendent. En terrasse ou en salle, \u00e0 proximit\u00e9 des pistes et du centre du village.\" \/>\n<meta property=\"og:site_name\" content=\"Les Angles\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-29T13:46:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lesangles.com\\\/es\\\/service\\\/surf-burger\\\/\",\"url\":\"https:\\\/\\\/lesangles.com\\\/es\\\/service\\\/surf-burger\\\/\",\"name\":\"SURF BURGER - Les Angles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lesangles.com\\\/es\\\/#website\"},\"datePublished\":\"2026-06-24T06:17:37+00:00\",\"dateModified\":\"2026-06-29T13:46:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lesangles.com\\\/es\\\/service\\\/surf-burger\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lesangles.com\\\/es\\\/service\\\/surf-burger\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lesangles.com\\\/es\\\/service\\\/surf-burger\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lesangles.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Services\",\"item\":\"https:\\\/\\\/lesangles.com\\\/es\\\/service\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SURF BURGER\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lesangles.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/lesangles.com\\\/es\\\/\",\"name\":\"Les Angles\",\"description\":\"Station quatre saisons de ski dans les Pyr\u00e9n\u00e9es-Orientales\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lesangles.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SURF BURGER - Les Angles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lesangles.com\/es\/service\/surf-burger\/","og_locale":"es_ES","og_type":"article","og_title":"SURF BURGER - Les Angles","og_description":"Dans une ambiance tr\u00e8s seventies, hamburgers, paninis, am\u00e9ricains et croques vous attendent. En terrasse ou en salle, \u00e0 proximit\u00e9 des pistes et du centre du village.","og_site_name":"Les Angles","article_modified_time":"2026-06-29T13:46:00+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lesangles.com\/es\/service\/surf-burger\/","url":"https:\/\/lesangles.com\/es\/service\/surf-burger\/","name":"SURF BURGER - Les Angles","isPartOf":{"@id":"https:\/\/lesangles.com\/es\/#website"},"datePublished":"2026-06-24T06:17:37+00:00","dateModified":"2026-06-29T13:46:00+00:00","breadcrumb":{"@id":"https:\/\/lesangles.com\/es\/service\/surf-burger\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lesangles.com\/es\/service\/surf-burger\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lesangles.com\/es\/service\/surf-burger\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lesangles.com\/es\/"},{"@type":"ListItem","position":2,"name":"Services","item":"https:\/\/lesangles.com\/es\/service\/"},{"@type":"ListItem","position":3,"name":"SURF BURGER"}]},{"@type":"WebSite","@id":"https:\/\/lesangles.com\/es\/#website","url":"https:\/\/lesangles.com\/es\/","name":"Les Angles","description":"Station quatre saisons de ski dans les Pyr\u00e9n\u00e9es-Orientales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lesangles.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/lesangles.com\/es\/wp-json\/wp\/v2\/tsc_service\/94217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lesangles.com\/es\/wp-json\/wp\/v2\/tsc_service"}],"about":[{"href":"https:\/\/lesangles.com\/es\/wp-json\/wp\/v2\/types\/tsc_service"}],"wp:attachment":[{"href":"https:\/\/lesangles.com\/es\/wp-json\/wp\/v2\/media?parent=94217"}],"wp:term":[{"taxonomy":"tsc_cat_service","embeddable":true,"href":"https:\/\/lesangles.com\/es\/wp-json\/wp\/v2\/tsc_cat_service?post=94217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}