{"id":94117,"date":"2026-06-24T08:17:25","date_gmt":"2026-06-24T06:17:25","guid":{"rendered":"https:\/\/lesangles.com\/service\/aire-de-pique-nique-balcere\/"},"modified":"2026-06-29T15:45:46","modified_gmt":"2026-06-29T13:45:46","slug":"aire-de-pique-nique-balcere","status":"publish","type":"tsc_service","link":"https:\/\/lesangles.com\/es\/service\/aire-de-pique-nique-balcere\/","title":{"rendered":"AIRE DE PIQUE NIQUE BALC\u00c8RE"},"content":{"rendered":"<p>Aire de pique-nique avec places \u00e0 feu. Toilettes \u00e0 proximit\u00e9.<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false},"tsc_cat_service":[1273],"class_list":["post-94117","tsc_service","type-tsc_service","status-publish","hentry","tsc_cat_service-aire-de-pique-nique"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AIRE DE PIQUE NIQUE BALC\u00c8RE - Les Angles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lesangles.com\/es\/service\/aire-de-pique-nique-balcere\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AIRE DE PIQUE NIQUE BALC\u00c8RE - Les Angles\" \/>\n<meta property=\"og:description\" content=\"Aire de pique-nique avec places \u00e0 feu. Toilettes \u00e0 proximit\u00e9.\" \/>\n<meta property=\"og:site_name\" content=\"Les Angles\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-29T13:45:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lesangles.com\\\/es\\\/service\\\/aire-de-pique-nique-balcere\\\/\",\"url\":\"https:\\\/\\\/lesangles.com\\\/es\\\/service\\\/aire-de-pique-nique-balcere\\\/\",\"name\":\"AIRE DE PIQUE NIQUE BALC\u00c8RE - Les Angles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lesangles.com\\\/es\\\/#website\"},\"datePublished\":\"2026-06-24T06:17:25+00:00\",\"dateModified\":\"2026-06-29T13:45:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lesangles.com\\\/es\\\/service\\\/aire-de-pique-nique-balcere\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lesangles.com\\\/es\\\/service\\\/aire-de-pique-nique-balcere\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lesangles.com\\\/es\\\/service\\\/aire-de-pique-nique-balcere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lesangles.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Services\",\"item\":\"https:\\\/\\\/lesangles.com\\\/es\\\/service\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"AIRE DE PIQUE NIQUE BALC\u00c8RE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lesangles.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/lesangles.com\\\/es\\\/\",\"name\":\"Les Angles\",\"description\":\"Station quatre saisons de ski dans les Pyr\u00e9n\u00e9es-Orientales\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lesangles.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AIRE DE PIQUE NIQUE BALC\u00c8RE - Les Angles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lesangles.com\/es\/service\/aire-de-pique-nique-balcere\/","og_locale":"es_ES","og_type":"article","og_title":"AIRE DE PIQUE NIQUE BALC\u00c8RE - Les Angles","og_description":"Aire de pique-nique avec places \u00e0 feu. Toilettes \u00e0 proximit\u00e9.","og_site_name":"Les Angles","article_modified_time":"2026-06-29T13:45:46+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lesangles.com\/es\/service\/aire-de-pique-nique-balcere\/","url":"https:\/\/lesangles.com\/es\/service\/aire-de-pique-nique-balcere\/","name":"AIRE DE PIQUE NIQUE BALC\u00c8RE - Les Angles","isPartOf":{"@id":"https:\/\/lesangles.com\/es\/#website"},"datePublished":"2026-06-24T06:17:25+00:00","dateModified":"2026-06-29T13:45:46+00:00","breadcrumb":{"@id":"https:\/\/lesangles.com\/es\/service\/aire-de-pique-nique-balcere\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lesangles.com\/es\/service\/aire-de-pique-nique-balcere\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lesangles.com\/es\/service\/aire-de-pique-nique-balcere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lesangles.com\/es\/"},{"@type":"ListItem","position":2,"name":"Services","item":"https:\/\/lesangles.com\/es\/service\/"},{"@type":"ListItem","position":3,"name":"AIRE DE PIQUE NIQUE BALC\u00c8RE"}]},{"@type":"WebSite","@id":"https:\/\/lesangles.com\/es\/#website","url":"https:\/\/lesangles.com\/es\/","name":"Les Angles","description":"Station quatre saisons de ski dans les Pyr\u00e9n\u00e9es-Orientales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lesangles.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/lesangles.com\/es\/wp-json\/wp\/v2\/tsc_service\/94117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lesangles.com\/es\/wp-json\/wp\/v2\/tsc_service"}],"about":[{"href":"https:\/\/lesangles.com\/es\/wp-json\/wp\/v2\/types\/tsc_service"}],"wp:attachment":[{"href":"https:\/\/lesangles.com\/es\/wp-json\/wp\/v2\/media?parent=94117"}],"wp:term":[{"taxonomy":"tsc_cat_service","embeddable":true,"href":"https:\/\/lesangles.com\/es\/wp-json\/wp\/v2\/tsc_cat_service?post=94117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}