{"id":93198,"date":"2026-06-24T08:16:39","date_gmt":"2026-06-24T06:16:39","guid":{"rendered":"https:\/\/lesangles.com\/hebergement\/petrieux-cathy\/"},"modified":"2026-06-29T15:42:53","modified_gmt":"2026-06-29T13:42:53","slug":"petrieux-cathy","status":"publish","type":"tsc_hebergement","link":"https:\/\/lesangles.com\/es\/hebergement\/petrieux-cathy\/","title":{"rendered":"PETRIEUX CATHY"},"content":{"rendered":"<p>Bajo de casa de pueblo. T2 planta baja.  35m2. Planta baja con todas las comodidades. Cerca de todos los comercios, pistas, aeropuerto&#8230;<br \/>\nS\u00e1banas, toallas, trapos de cocina incluidos. Kit de bienvenida proporcionado (esponjas, papel higi\u00e9nico, etc.).<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false},"tsc_cat_hebergement":[1334],"class_list":["post-93198","tsc_hebergement","type-tsc_hebergement","status-publish","hentry","tsc_cat_hebergement-apartamentos-de-vacaciones-amueblados"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PETRIEUX CATHY - Les Angles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lesangles.com\/es\/hebergement\/petrieux-cathy\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PETRIEUX CATHY - Les Angles\" \/>\n<meta property=\"og:description\" content=\"Bajo de casa de pueblo. T2 planta baja. 35m2. Planta baja con todas las comodidades. Cerca de todos los comercios, pistas, aeropuerto&#8230; S\u00e1banas, toallas, trapos de cocina incluidos. Kit de bienvenida proporcionado (esponjas, papel higi\u00e9nico, etc.).\" \/>\n<meta property=\"og:site_name\" content=\"Les Angles\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-29T13:42:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lesangles.com\\\/es\\\/hebergement\\\/petrieux-cathy\\\/\",\"url\":\"https:\\\/\\\/lesangles.com\\\/es\\\/hebergement\\\/petrieux-cathy\\\/\",\"name\":\"PETRIEUX CATHY - Les Angles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lesangles.com\\\/es\\\/#website\"},\"datePublished\":\"2026-06-24T06:16:39+00:00\",\"dateModified\":\"2026-06-29T13:42:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lesangles.com\\\/es\\\/hebergement\\\/petrieux-cathy\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lesangles.com\\\/es\\\/hebergement\\\/petrieux-cathy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lesangles.com\\\/es\\\/hebergement\\\/petrieux-cathy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lesangles.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"H\u00e9bergements\",\"item\":\"https:\\\/\\\/lesangles.com\\\/es\\\/hebergement\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PETRIEUX CATHY\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lesangles.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/lesangles.com\\\/es\\\/\",\"name\":\"Les Angles\",\"description\":\"Station quatre saisons de ski dans les Pyr\u00e9n\u00e9es-Orientales\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lesangles.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PETRIEUX CATHY - Les Angles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lesangles.com\/es\/hebergement\/petrieux-cathy\/","og_locale":"es_ES","og_type":"article","og_title":"PETRIEUX CATHY - Les Angles","og_description":"Bajo de casa de pueblo. T2 planta baja. 35m2. Planta baja con todas las comodidades. Cerca de todos los comercios, pistas, aeropuerto&#8230; S\u00e1banas, toallas, trapos de cocina incluidos. Kit de bienvenida proporcionado (esponjas, papel higi\u00e9nico, etc.).","og_site_name":"Les Angles","article_modified_time":"2026-06-29T13:42:53+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lesangles.com\/es\/hebergement\/petrieux-cathy\/","url":"https:\/\/lesangles.com\/es\/hebergement\/petrieux-cathy\/","name":"PETRIEUX CATHY - Les Angles","isPartOf":{"@id":"https:\/\/lesangles.com\/es\/#website"},"datePublished":"2026-06-24T06:16:39+00:00","dateModified":"2026-06-29T13:42:53+00:00","breadcrumb":{"@id":"https:\/\/lesangles.com\/es\/hebergement\/petrieux-cathy\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lesangles.com\/es\/hebergement\/petrieux-cathy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lesangles.com\/es\/hebergement\/petrieux-cathy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lesangles.com\/es\/"},{"@type":"ListItem","position":2,"name":"H\u00e9bergements","item":"https:\/\/lesangles.com\/es\/hebergement\/"},{"@type":"ListItem","position":3,"name":"PETRIEUX CATHY"}]},{"@type":"WebSite","@id":"https:\/\/lesangles.com\/es\/#website","url":"https:\/\/lesangles.com\/es\/","name":"Les Angles","description":"Station quatre saisons de ski dans les Pyr\u00e9n\u00e9es-Orientales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lesangles.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/lesangles.com\/es\/wp-json\/wp\/v2\/tsc_hebergement\/93198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lesangles.com\/es\/wp-json\/wp\/v2\/tsc_hebergement"}],"about":[{"href":"https:\/\/lesangles.com\/es\/wp-json\/wp\/v2\/types\/tsc_hebergement"}],"wp:attachment":[{"href":"https:\/\/lesangles.com\/es\/wp-json\/wp\/v2\/media?parent=93198"}],"wp:term":[{"taxonomy":"tsc_cat_hebergement","embeddable":true,"href":"https:\/\/lesangles.com\/es\/wp-json\/wp\/v2\/tsc_cat_hebergement?post=93198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}