{"id":94302,"date":"2026-06-24T08:17:33","date_gmt":"2026-06-24T06:17:33","guid":{"rendered":"https:\/\/lesangles.com\/service\/la-fermette\/"},"modified":"2026-06-29T15:46:13","modified_gmt":"2026-06-29T13:46:13","slug":"la-fermette","status":"publish","type":"tsc_service","link":"https:\/\/lesangles.com\/en\/service\/la-fermette\/","title":{"rendered":"LA FERMETTE"},"content":{"rendered":"<p>Restaurant \u2013 Traditional cuisine \u2013 Mountain specialties \u2013 Bruschettas \u2013 Local products.<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false},"tsc_cat_service":[1478],"class_list":["post-94302","tsc_service","type-tsc_service","status-publish","hentry","tsc_cat_service-cellarman"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LA FERMETTE - Les Angles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lesangles.com\/en\/service\/la-fermette\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LA FERMETTE - Les Angles\" \/>\n<meta property=\"og:description\" content=\"Restaurant \u2013 Traditional cuisine \u2013 Mountain specialties \u2013 Bruschettas \u2013 Local products.\" \/>\n<meta property=\"og:site_name\" content=\"Les Angles\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-29T13:46:13+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lesangles.com\\\/en\\\/service\\\/la-fermette\\\/\",\"url\":\"https:\\\/\\\/lesangles.com\\\/en\\\/service\\\/la-fermette\\\/\",\"name\":\"LA FERMETTE - Les Angles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lesangles.com\\\/en\\\/#website\"},\"datePublished\":\"2026-06-24T06:17:33+00:00\",\"dateModified\":\"2026-06-29T13:46:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lesangles.com\\\/en\\\/service\\\/la-fermette\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lesangles.com\\\/en\\\/service\\\/la-fermette\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lesangles.com\\\/en\\\/service\\\/la-fermette\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lesangles.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Services\",\"item\":\"https:\\\/\\\/lesangles.com\\\/en\\\/service\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"LA FERMETTE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lesangles.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/lesangles.com\\\/en\\\/\",\"name\":\"Les Angles\",\"description\":\"Station quatre saisons de ski dans les Pyr\u00e9n\u00e9es-Orientales\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lesangles.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LA FERMETTE - Les Angles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lesangles.com\/en\/service\/la-fermette\/","og_locale":"en_US","og_type":"article","og_title":"LA FERMETTE - Les Angles","og_description":"Restaurant \u2013 Traditional cuisine \u2013 Mountain specialties \u2013 Bruschettas \u2013 Local products.","og_site_name":"Les Angles","article_modified_time":"2026-06-29T13:46:13+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lesangles.com\/en\/service\/la-fermette\/","url":"https:\/\/lesangles.com\/en\/service\/la-fermette\/","name":"LA FERMETTE - Les Angles","isPartOf":{"@id":"https:\/\/lesangles.com\/en\/#website"},"datePublished":"2026-06-24T06:17:33+00:00","dateModified":"2026-06-29T13:46:13+00:00","breadcrumb":{"@id":"https:\/\/lesangles.com\/en\/service\/la-fermette\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lesangles.com\/en\/service\/la-fermette\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lesangles.com\/en\/service\/la-fermette\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lesangles.com\/en\/"},{"@type":"ListItem","position":2,"name":"Services","item":"https:\/\/lesangles.com\/en\/service\/"},{"@type":"ListItem","position":3,"name":"LA FERMETTE"}]},{"@type":"WebSite","@id":"https:\/\/lesangles.com\/en\/#website","url":"https:\/\/lesangles.com\/en\/","name":"Les Angles","description":"Station quatre saisons de ski dans les Pyr\u00e9n\u00e9es-Orientales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lesangles.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/lesangles.com\/en\/wp-json\/wp\/v2\/tsc_service\/94302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lesangles.com\/en\/wp-json\/wp\/v2\/tsc_service"}],"about":[{"href":"https:\/\/lesangles.com\/en\/wp-json\/wp\/v2\/types\/tsc_service"}],"wp:attachment":[{"href":"https:\/\/lesangles.com\/en\/wp-json\/wp\/v2\/media?parent=94302"}],"wp:term":[{"taxonomy":"tsc_cat_service","embeddable":true,"href":"https:\/\/lesangles.com\/en\/wp-json\/wp\/v2\/tsc_cat_service?post=94302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}