{"id":93836,"date":"2026-06-24T08:17:06","date_gmt":"2026-06-24T06:17:06","guid":{"rendered":"https:\/\/lesangles.com\/evenement\/tesoros-de-la-natura\/"},"modified":"2026-06-29T15:44:48","modified_gmt":"2026-06-29T13:44:48","slug":"tesoros-de-la-natura","status":"publish","type":"tsc_evenement","link":"https:\/\/lesangles.com\/ca\/evenement\/tesoros-de-la-natura\/","title":{"rendered":"Tesoros de la natura"},"content":{"rendered":"<p>Una passejada de descobriment amb en Guillaume, un guia de muntanya, per veure l&#8217;invisible: rastres d&#8217;animals, els secrets de les plantes i contes d&#8217;elfs.<br \/>\nA partir de 5 anys<\/p>\n<p>PLACES LIMITADES. INSCRIPCI\u00d3 EN L\u00cdNIA A \u00ablesangles.com\u00bb<\/p>\n<p>Punt de trobada: Pla Del Mir<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false},"tsc_cat_evenement":[1397],"class_list":["post-93836","tsc_evenement","type-tsc_evenement","status-publish","hentry","tsc_cat_evenement-senderisme"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tesoros de la natura - Les Angles<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lesangles.com\/ca\/evenement\/tesoros-de-la-natura\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tesoros de la natura - Les Angles\" \/>\n<meta property=\"og:description\" content=\"Una passejada de descobriment amb en Guillaume, un guia de muntanya, per veure l&#8217;invisible: rastres d&#8217;animals, els secrets de les plantes i contes d&#8217;elfs. A partir de 5 anys PLACES LIMITADES. INSCRIPCI\u00d3 EN L\u00cdNIA A \u00ablesangles.com\u00bb Punt de trobada: Pla Del Mir\" \/>\n<meta property=\"og:site_name\" content=\"Les Angles\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-29T13:44:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lesangles.com\\\/ca\\\/evenement\\\/tesoros-de-la-natura\\\/\",\"url\":\"https:\\\/\\\/lesangles.com\\\/ca\\\/evenement\\\/tesoros-de-la-natura\\\/\",\"name\":\"Tesoros de la natura - Les Angles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lesangles.com\\\/ca\\\/#website\"},\"datePublished\":\"2026-06-24T06:17:06+00:00\",\"dateModified\":\"2026-06-29T13:44:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lesangles.com\\\/ca\\\/evenement\\\/tesoros-de-la-natura\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lesangles.com\\\/ca\\\/evenement\\\/tesoros-de-la-natura\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lesangles.com\\\/ca\\\/evenement\\\/tesoros-de-la-natura\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lesangles.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9v\u00e9nements\",\"item\":\"https:\\\/\\\/lesangles.com\\\/ca\\\/evenement\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tesoros de la natura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lesangles.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/lesangles.com\\\/ca\\\/\",\"name\":\"Les Angles\",\"description\":\"Station quatre saisons de ski dans les Pyr\u00e9n\u00e9es-Orientales\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lesangles.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tesoros de la natura - Les Angles","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lesangles.com\/ca\/evenement\/tesoros-de-la-natura\/","og_locale":"ca_ES","og_type":"article","og_title":"Tesoros de la natura - Les Angles","og_description":"Una passejada de descobriment amb en Guillaume, un guia de muntanya, per veure l&#8217;invisible: rastres d&#8217;animals, els secrets de les plantes i contes d&#8217;elfs. A partir de 5 anys PLACES LIMITADES. INSCRIPCI\u00d3 EN L\u00cdNIA A \u00ablesangles.com\u00bb Punt de trobada: Pla Del Mir","og_site_name":"Les Angles","article_modified_time":"2026-06-29T13:44:48+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lesangles.com\/ca\/evenement\/tesoros-de-la-natura\/","url":"https:\/\/lesangles.com\/ca\/evenement\/tesoros-de-la-natura\/","name":"Tesoros de la natura - Les Angles","isPartOf":{"@id":"https:\/\/lesangles.com\/ca\/#website"},"datePublished":"2026-06-24T06:17:06+00:00","dateModified":"2026-06-29T13:44:48+00:00","breadcrumb":{"@id":"https:\/\/lesangles.com\/ca\/evenement\/tesoros-de-la-natura\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lesangles.com\/ca\/evenement\/tesoros-de-la-natura\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lesangles.com\/ca\/evenement\/tesoros-de-la-natura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lesangles.com\/ca\/"},{"@type":"ListItem","position":2,"name":"\u00c9v\u00e9nements","item":"https:\/\/lesangles.com\/ca\/evenement\/"},{"@type":"ListItem","position":3,"name":"Tesoros de la natura"}]},{"@type":"WebSite","@id":"https:\/\/lesangles.com\/ca\/#website","url":"https:\/\/lesangles.com\/ca\/","name":"Les Angles","description":"Station quatre saisons de ski dans les Pyr\u00e9n\u00e9es-Orientales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lesangles.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"_links":{"self":[{"href":"https:\/\/lesangles.com\/ca\/wp-json\/wp\/v2\/tsc_evenement\/93836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lesangles.com\/ca\/wp-json\/wp\/v2\/tsc_evenement"}],"about":[{"href":"https:\/\/lesangles.com\/ca\/wp-json\/wp\/v2\/types\/tsc_evenement"}],"wp:attachment":[{"href":"https:\/\/lesangles.com\/ca\/wp-json\/wp\/v2\/media?parent=93836"}],"wp:term":[{"taxonomy":"tsc_cat_evenement","embeddable":true,"href":"https:\/\/lesangles.com\/ca\/wp-json\/wp\/v2\/tsc_cat_evenement?post=93836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}